{"id":11150,"date":"2026-05-26T21:18:21","date_gmt":"2026-05-26T13:18:21","guid":{"rendered":"https:\/\/www.rutace.com\/?post_type=product&#038;p=11150"},"modified":"2026-06-11T16:46:37","modified_gmt":"2026-06-11T08:46:37","slug":"color-amplifie-4","status":"publish","type":"product","link":"https:\/\/www.rutace.com\/es\/producto\/color-amplifie-4\/","title":{"rendered":"Amplificador de color KS-551N"},"content":{"rendered":"<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1. Funciones principales<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Este es un amplificador digital de alta precisi\u00f3n para sensores de color, con fuente de luz LED blanca y sensor RGB. Admite m\u00faltiples modos de salida, incluidos NPN\/PNP y RS485, y cuenta con una pantalla digital y configuraci\u00f3n de aprendizaje con un solo bot\u00f3n. Ofrece una gran capacidad antiinterferencias y es capaz de distinguir de manera estable diferencias sutiles de color.<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2. Distancia de detecci\u00f3n<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Distancia t\u00edpica de detecci\u00f3n <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10-50 mm<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">.<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3. Velocidad de respuesta<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Velocidad de respuesta <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">250 \u03bcs<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">, cumpliendo con los requisitos de las l\u00edneas de producci\u00f3n de alta velocidad.<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4. Aplicaciones t\u00edpicas<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Detecci\u00f3n de marcas de color en empaques, verificaci\u00f3n de empaques de productos alimenticios y farmac\u00e9uticos, posicionamiento de componentes electr\u00f3nicos, detecci\u00f3n de color en telas textiles, identificaci\u00f3n de color en la clasificaci\u00f3n log\u00edstica.<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1. Funciones principales<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Este es un amplificador digital de alta precisi\u00f3n para sensores de color, con fuente de luz LED blanca y sensor RGB. Admite m\u00faltiples modos de salida, incluidos NPN\/PNP y RS485, y cuenta con una pantalla digital y configuraci\u00f3n de aprendizaje con un solo bot\u00f3n. Ofrece una gran capacidad antiinterferencias y es capaz de distinguir de manera estable diferencias sutiles de color.<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2. Distancia de detecci\u00f3n<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Distancia t\u00edpica de detecci\u00f3n <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10-50 mm<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">.<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3. Velocidad de respuesta<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Velocidad de respuesta <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">250 \u03bcs<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">, cumpliendo con los requisitos de las l\u00edneas de producci\u00f3n de alta velocidad.<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4. Aplicaciones t\u00edpicas<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Detecci\u00f3n de marcas de color en empaques, verificaci\u00f3n de empaques de productos alimenticios y farmac\u00e9uticos, posicionamiento de componentes electr\u00f3nicos, detecci\u00f3n de color en telas textiles, identificaci\u00f3n de color en la clasificaci\u00f3n log\u00edstica.<\/span><\/span><\/p>","protected":false},"featured_media":11151,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[140],"product_tag":[],"class_list":["post-11150","product","type-product","status-publish","has-post-thumbnail","product_cat-color-sensor","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/comments?post=11150"}],"version-history":[{"count":3,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11150\/revisions"}],"predecessor-version":[{"id":11647,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11150\/revisions\/11647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/media\/11151"}],"wp:attachment":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/media?parent=11150"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_brand?post=11150"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_cat?post=11150"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_tag?post=11150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}