{"id":11034,"date":"2026-05-26T19:41:08","date_gmt":"2026-05-26T11:41:08","guid":{"rendered":"https:\/\/www.rutace.com\/?post_type=product&#038;p=11034"},"modified":"2026-06-11T17:04:21","modified_gmt":"2026-06-11T09:04:21","slug":"fiber-endfiber-amplifier-2","status":"publish","type":"product","link":"https:\/\/www.rutace.com\/es\/producto\/fiber-endfiber-amplifier-2\/","title":{"rendered":"Extremo de fibra + Amplificador de fibra DP-M3"},"content":{"rendered":"<h3>Principio b\u00e1sico de funcionamiento<\/h3>\n<p>Esto es un <strong>cabezal de fibra \u00f3ptica protegido por una manguera met\u00e1lica<\/strong>, que act\u00faa como \u201csonda frontal\u201d del sensor de fibra \u00f3ptica y que, junto con un amplificador de fibra, lleva a cabo la detecci\u00f3n. La fibra \u00f3ptica integrada en el cabezal de fibra est\u00e1 conectada al amplificador de fibra por un extremo y dirigida hacia el \u00e1rea de detecci\u00f3n por el otro. La se\u00f1al luminosa emitida por el amplificador se transmite a trav\u00e9s de la fibra \u00f3ptica hasta el extremo de la sonda. Tras entrar en contacto con el objeto objetivo, la luz reflejada\/transmitida viaja de regreso a lo largo de la fibra \u00f3ptica hasta el amplificador, completando as\u00ed el proceso de detecci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<h3>Principio b\u00e1sico de funcionamiento<\/h3>\n<p>Esto es un <strong>cabezal de fibra \u00f3ptica protegido por una manguera met\u00e1lica<\/strong>, que act\u00faa como \u201csonda frontal\u201d del sensor de fibra \u00f3ptica y que, junto con un amplificador de fibra, lleva a cabo la detecci\u00f3n. La fibra \u00f3ptica integrada en el cabezal de fibra est\u00e1 conectada al amplificador de fibra por un extremo y dirigida hacia el \u00e1rea de detecci\u00f3n por el otro. La se\u00f1al luminosa emitida por el amplificador se transmite a trav\u00e9s de la fibra \u00f3ptica hasta el extremo de la sonda. Tras entrar en contacto con el objeto objetivo, la luz reflejada\/transmitida viaja de regreso a lo largo de la fibra \u00f3ptica hasta el amplificador, completando as\u00ed el proceso de detecci\u00f3n.<\/p>","protected":false},"featured_media":11035,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[129],"product_tag":[],"class_list":["post-11034","product","type-product","status-publish","has-post-thumbnail","product_cat-fiber-sensor","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/comments?post=11034"}],"version-history":[{"count":3,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11034\/revisions"}],"predecessor-version":[{"id":11661,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11034\/revisions\/11661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/media\/11035"}],"wp:attachment":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/media?parent=11034"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_brand?post=11034"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_cat?post=11034"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_tag?post=11034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}