{"id":11024,"date":"2026-05-26T19:36:28","date_gmt":"2026-05-26T11:36:28","guid":{"rendered":"https:\/\/www.rutace.com\/?post_type=product&#038;p=11024"},"modified":"2026-06-11T17:01:32","modified_gmt":"2026-06-11T09:01:32","slug":"area-fiber-optic-sensor","status":"publish","type":"product","link":"https:\/\/www.rutace.com\/es\/producto\/area-fiber-optic-sensor\/","title":{"rendered":"Sensor de fibra \u00f3ptica de \u00e1rea RT-E40"},"content":{"rendered":"<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Principio operativo fundamental<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Se trata de una sonda de fibra \u00f3ptica especialmente dise\u00f1ada que funciona con amplificadores de fibra \u00f3ptica para lograr una detecci\u00f3n continua de \u00e1reas extensas. La se\u00f1al luminosa emitida por el amplificador de fibra \u00f3ptica se transmite a trav\u00e9s de una matriz interna de fibra multihilera hasta el extremo de la sonda en forma de varilla, donde es modelada por estructuras de lentes \u00f3pticas y gu\u00edas de luz para formar una cortina de luz lineal continua. Las sondas se utilizan en pares (transmisor + receptor). Cuando un objeto bloquea la cortina de luz, la intensidad de la se\u00f1al luminosa en el receptor disminuye, y el amplificador de fibra \u00f3ptica detecta este cambio en la se\u00f1al y emite una se\u00f1al de conmutaci\u00f3n.<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Principio operativo fundamental<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Se trata de una sonda de fibra \u00f3ptica especialmente dise\u00f1ada que funciona con amplificadores de fibra \u00f3ptica para lograr una detecci\u00f3n continua de \u00e1reas extensas. La se\u00f1al luminosa emitida por el amplificador de fibra \u00f3ptica se transmite a trav\u00e9s de una matriz interna de fibra multihilera hasta el extremo de la sonda en forma de varilla, donde es modelada por estructuras de lentes \u00f3pticas y gu\u00edas de luz para formar una cortina de luz lineal continua. Las sondas se utilizan en pares (transmisor + receptor). Cuando un objeto bloquea la cortina de luz, la intensidad de la se\u00f1al luminosa en el receptor disminuye, y el amplificador de fibra \u00f3ptica detecta este cambio en la se\u00f1al y emite una se\u00f1al de conmutaci\u00f3n.<\/span><\/span><\/p>","protected":false},"featured_media":11025,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[129],"product_tag":[],"class_list":["post-11024","product","type-product","status-publish","has-post-thumbnail","product_cat-fiber-sensor","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/comments?post=11024"}],"version-history":[{"count":3,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11024\/revisions"}],"predecessor-version":[{"id":11659,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product\/11024\/revisions\/11659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/media\/11025"}],"wp:attachment":[{"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/media?parent=11024"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_brand?post=11024"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_cat?post=11024"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.rutace.com\/es\/wp-json\/wp\/v2\/product_tag?post=11024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}